{"id":1632,"date":"2022-05-18T17:51:28","date_gmt":"2022-05-18T15:51:28","guid":{"rendered":"https:\/\/karl-schubert-schule.at\/?page_id=1632"},"modified":"2026-05-08T15:46:49","modified_gmt":"2026-05-08T13:46:49","slug":"aktuelles","status":"publish","type":"page","link":"https:\/\/karl-schubert-schule.at\/en\/aktuelles\/","title":{"rendered":"News"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1632\" class=\"elementor elementor-1632\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-124736d0 elementor-section-height-min-height elementor-section-items-stretch elementor-section-full_width elementor-section-height-default\" data-id=\"124736d0\" data-element_type=\"section\" data-e-type=\"section\" id=\"top\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-691c041e\" data-id=\"691c041e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6505dff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6505dff\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7fc9daa\" data-id=\"7fc9daa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbcf5d7 elementor-widget elementor-widget-image\" data-id=\"dbcf5d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"741\" height=\"1024\" src=\"https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Plakat_Fraberger_sw_1-741x1024.jpg\" class=\"attachment-large size-large wp-image-4527\" alt=\"\" srcset=\"https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Plakat_Fraberger_sw_1-741x1024.jpg 741w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Plakat_Fraberger_sw_1-217x300.jpg 217w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Plakat_Fraberger_sw_1-768x1062.jpg 768w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Plakat_Fraberger_sw_1-1111x1536.jpg 1111w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Plakat_Fraberger_sw_1-1482x2048.jpg 1482w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Plakat_Fraberger_sw_1-9x12.jpg 9w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Plakat_Fraberger_sw_1-scaled.jpg 1852w\" sizes=\"(max-width: 741px) 100vw, 741px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d752f44\" data-id=\"d752f44\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f5d2945 elementor-widget elementor-widget-image\" data-id=\"f5d2945\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"698\" height=\"1024\" src=\"https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Einladung-Buchpraesentation-Georg-Fraberger_2-698x1024.jpg\" class=\"attachment-large size-large wp-image-4526\" alt=\"\" srcset=\"https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Einladung-Buchpraesentation-Georg-Fraberger_2-698x1024.jpg 698w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Einladung-Buchpraesentation-Georg-Fraberger_2-204x300.jpg 204w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Einladung-Buchpraesentation-Georg-Fraberger_2-768x1127.jpg 768w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Einladung-Buchpraesentation-Georg-Fraberger_2-1047x1536.jpg 1047w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Einladung-Buchpraesentation-Georg-Fraberger_2-1396x2048.jpg 1396w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Einladung-Buchpraesentation-Georg-Fraberger_2-8x12.jpg 8w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/05\/Einladung-Buchpraesentation-Georg-Fraberger_2-scaled.jpg 1745w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40e660e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40e660e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d59b385\" data-id=\"d59b385\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0b293a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0b293a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b9b2f99\" data-id=\"b9b2f99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-298933e elementor-widget elementor-widget-text-editor\" data-id=\"298933e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\"><strong>Einladung zur <\/strong><br \/><strong>Schulfeier am Mittwoch<\/strong><br \/><strong>den 17. Juni 2026<\/strong><\/h1><h2 style=\"text-align: center;\"><strong>von 9 bis 10 Uhr<\/strong><\/h2><p style=\"text-align: center;\">Die Sch\u00fclerinnen und Sch\u00fcler pr\u00e4sentieren auf der B\u00fchne, was sie dieses Schuljahr schon gelernt haben.<\/p><p style=\"text-align: center;\">Wir informieren an diesem Vormittag auch \u00fcber unsere Schule, mit Gespr\u00e4chen und einer Ausstellung von Werkst\u00fccken unserer Sch\u00fclerinnen und Sch\u00fcler. Gerne laden wir Sie anschlie\u00dfend zu Kaffee und Kuchen ein.<\/p><p style=\"text-align: center;\"><strong>In der Zeit von 10 bis 12:00 Uhr haben Sie auch die M\u00f6glichkeit, sich \u00fcber F\u00f6rderleistungen des Fonds Soziales Wien direkt zu informieren. Berater\/innen des FSW sind in dieser Zeit mit einem eigenen Stand im Foyer unserer Schule anwesend.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bbfd9af elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbfd9af\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a78c773\" data-id=\"a78c773\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b27634 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b27634\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-772c5fb\" data-id=\"772c5fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60ae0b6 elementor-widget elementor-widget-image\" data-id=\"60ae0b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/02\/DSC02216-1024x683.jpg\" class=\"attachment-large size-large wp-image-4504\" alt=\"\" srcset=\"https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/02\/DSC02216-1024x683.jpg 1024w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/02\/DSC02216-300x200.jpg 300w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/02\/DSC02216-768x512.jpg 768w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/02\/DSC02216-1536x1024.jpg 1536w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/02\/DSC02216-2048x1365.jpg 2048w, https:\/\/karl-schubert-schule.at\/wp-content\/uploads\/2026\/02\/DSC02216-18x12.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c74a476 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c74a476\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca391d0\" data-id=\"ca391d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Einladung zur Schulfeier am Mittwochden 17. Juni 2026 von 9 bis 10 Uhr Die Sch\u00fclerinnen und Sch\u00fcler pr\u00e4sentieren auf der B\u00fchne, was sie dieses Schuljahr schon gelernt haben. Wir informieren an diesem Vormittag auch \u00fcber unsere Schule, mit Gespr\u00e4chen und einer Ausstellung von Werkst\u00fccken unserer Sch\u00fclerinnen und Sch\u00fcler. Gerne laden wir Sie anschlie\u00dfend zu Kaffee [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1632","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/karl-schubert-schule.at\/en\/wp-json\/wp\/v2\/pages\/1632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/karl-schubert-schule.at\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/karl-schubert-schule.at\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/karl-schubert-schule.at\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/karl-schubert-schule.at\/en\/wp-json\/wp\/v2\/comments?post=1632"}],"version-history":[{"count":163,"href":"https:\/\/karl-schubert-schule.at\/en\/wp-json\/wp\/v2\/pages\/1632\/revisions"}],"predecessor-version":[{"id":4540,"href":"https:\/\/karl-schubert-schule.at\/en\/wp-json\/wp\/v2\/pages\/1632\/revisions\/4540"}],"wp:attachment":[{"href":"https:\/\/karl-schubert-schule.at\/en\/wp-json\/wp\/v2\/media?parent=1632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}